{"id":4971,"date":"2025-03-21T07:54:25","date_gmt":"2025-03-21T06:54:25","guid":{"rendered":"https:\/\/tragos.gr\/?p=4971"},"modified":"2025-03-28T08:02:52","modified_gmt":"2025-03-28T07:02:52","slug":"21-03-25-fruehling-willkommen","status":"publish","type":"post","link":"https:\/\/tragos.gr\/de\/21-03-25-fruehling-willkommen\/","title":{"rendered":"21.03.25 &#8212; Fr\u00fchling, willkommen!"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4971\" class=\"elementor elementor-4971 elementor-4932\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-28fa158 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"28fa158\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7ad95dc\" data-id=\"7ad95dc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-42704c2 elementor-widget elementor-widget-text-editor\" data-id=\"42704c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"et_pb_module et_pb_text et_pb_text_3 et_pb_text_align_left et_pb_bg_layout_light et_had_animation\"><div class=\"et_pb_text_inner\"><p style=\"text-align: center;\">21.03.2025<\/p><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-087cc06 elementor-widget elementor-widget-heading\" data-id=\"087cc06\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Fr\u00fchling, willkommen!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-167440b elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"167440b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f7a115d elementor-widget elementor-widget-image\" data-id=\"f7a115d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/tragos.gr\/wp-content\/uploads\/elementor\/thumbs\/Tragos-Diary-210325-img-1-r3hbmk6eac9md2hv2b0ad60ksrh3bz56f3fbwtdssg.webp\" title=\"Tragos-Diary-210325-img-1\" alt=\"Tragos-Diary-210325-img-1\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-02b19bc elementor-widget elementor-widget-text-editor\" data-id=\"02b19bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><em>Der Fr\u00fchling in den Hainen!<\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b3e2724 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b3e2724\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-460cfec\" data-id=\"460cfec\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0e714ff elementor-widget elementor-widget-text-editor\" data-id=\"0e714ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"et_pb_module et_pb_text et_pb_text_3 et_pb_text_align_left et_pb_bg_layout_light et_had_animation\"><div class=\"et_pb_text_inner\"><p>Der Fr\u00fchling, der heute beginnt, findet die meisten Olivenhaine in ausgezeichnetem Zustand!<\/p><p>Der vergangene Winter war nicht \u201egro\u00dfartig\u201c, aber viel besser als die der letzten Jahre. Die B\u00e4ume haben die K\u00e4lte und das Wasser bekommen, das sie ben\u00f6tigen, und profitieren von Eltons guter Pflege, besonders vom Herbstschnitt und der D\u00fcngung mit Ziegenmist. Sie treiben gut aus und beginnen bereits zu knospen (und das sehr zufriedenstellend)!<\/p><p>Nun ist es wichtig, dass das Wetter \u201emild\u201c bleibt, ohne fr\u00fche Hitzewellen und pl\u00f6tzliche Ver\u00e4nderungen, die die Knospen und bald auch die Bl\u00fcten sch\u00e4digen k\u00f6nnten.&#8220;<\/p><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-02505c9\" data-id=\"02505c9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-138e723 elementor-arrows-position-outside elementor--h-position-center elementor--v-position-middle elementor-widget elementor-widget-slides\" data-id=\"138e723\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;autoplay_speed&quot;:8000,&quot;transition_speed&quot;:1000,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\r\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\" dir=\"ltr\" data-animation=\"fadeInUp\">\r\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-3cdc964 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"Tragos-Diary-210325-img-2\"><\/div><div class=\"elementor-background-overlay\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-description\">Ein robuster Baum!<\/div><\/div><\/div><\/div><div class=\"elementor-repeater-item-836bd2d swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"Tragos-Diary-210325-img-3\"><\/div><div class=\"elementor-background-overlay\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-description\">Dichtes, gesundes Blattwerk<\/div><\/div><\/div><\/div><div class=\"elementor-repeater-item-1e4ef3f swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"Tragos-Diary-210325-img-4\"><\/div><div class=\"elementor-background-overlay\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-description\">Elton inspizierend\u2026<\/div><\/div><\/div><\/div><div class=\"elementor-repeater-item-272469e swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"Tragos-Diary-210325-img-5\"><\/div><div class=\"elementor-background-overlay\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-description\">Zweige voll von Bl\u00fctenknospen!<\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Previous slide\">\r\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Next slide\">\r\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dd14675 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dd14675\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b0967e1\" data-id=\"b0967e1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-86b303f elementor-widget elementor-widget-image\" data-id=\"86b303f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/tragos.gr\/wp-content\/uploads\/2025\/03\/Tragos-Diary-210325-img-6.webp\" title=\"Tragos-Diary-210325-img-6\" alt=\"Tragos-Diary-210325-img-6\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-127b367 elementor-widget elementor-widget-text-editor\" data-id=\"127b367\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><em>Dynamische Pubertierende!<\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-551ce7b\" data-id=\"551ce7b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c5327d0 elementor-widget elementor-widget-text-editor\" data-id=\"c5327d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Unser junger \u2013 alter Olivenhain, der aus den verbrannten Olivenb\u00e4umen im Bogdani-Gebiet entstanden ist (siehe den Eintrag vom 14.02.2024), ist voller Kraft und Vitalit\u00e4t! Das Einzige, was unsere Wildolivenb\u00e4umchen jetzt brauchen, ist das Entfernen der Wasserschosse, obwohl deren Wachstum aufgrund ihren starken Wurzelsysteme selbst durch diese nicht wesentlich behindert wird.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2cb992a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2cb992a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-83db4c2\" data-id=\"83db4c2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8c81624 elementor-widget elementor-widget-text-editor\" data-id=\"8c81624\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"et_pb_module et_pb_text et_pb_text_3 et_pb_text_align_left et_pb_bg_layout_light et_had_animation\"><div class=\"et_pb_text_inner\"><p>Obwohl der allgemeine Zustand gut ist, haben wir auch Probleme, da Voulgaraki vom <em>spilocaea oleagina<strong>\u00a0<\/strong><\/em>befallen ist, und zwar ziemlich intensiv! <em>Spilocaea oleagina<\/em><strong>\u00a0<\/strong>ist ein Pilz, der die Bl\u00e4tter abt\u00f6tet und so den Baum schw\u00e4cht.<\/p><p>Leider kann nichts gegen die betroffenen Bl\u00e4tter unternommen werden, die verloren gehen werden. Jede Pflege wird sich auf die gesunden Bl\u00e4tter konzentrieren, die \u00fcbrig bleiben, und auf die, die noch kommen werden. Aus diesem Grund wird Elton jetzt schnell handeln, so dass die B\u00e4ume noch m\u00f6glichst von der Wachstumsperiode profitieren bevor diese endet, wenn das Wetter sich erw\u00e4rmt.<\/p><p>Unter diesen Bedingungen ist es unwahrscheinlich, dass es in Voulgaraki in diesem Jahr eine Ernte geben wird. Wenn das Wetter mitspielt, ist das Ziel, dass diese Olivenhaine beim Beginn des neuen Olivenzyklus im Winter 2025\/2026 wieder in gutem Zustand sind.<\/p><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8edffda\" data-id=\"8edffda\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fb51334 elementor-widget elementor-widget-image\" data-id=\"fb51334\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/tragos.gr\/wp-content\/uploads\/elementor\/thumbs\/Tragos-Diary-210325-img-7-r3hc21kov3gnlu07nhy1xrcx295r4hm07qa9hwfcao.webp\" title=\"Tragos-Diary-210325-img-7\" alt=\"Tragos-Diary-210325-img-7\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9777c7c elementor-widget elementor-widget-text-editor\" data-id=\"9777c7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><em>Erscheinung und Wirkung des Pilzes spilocaea oleaginea<\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-33895e0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"33895e0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-342fdb6\" data-id=\"342fdb6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-711f309 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"711f309\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/tragos.gr\/de\/tagebuch\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Zur\u00fcck zum Tagebuch<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>21.03.2025 Fr\u00fchling, willkommen! Der Fr\u00fchling in den Hainen! Der Fr\u00fchling, der heute beginnt, findet die meisten Olivenhaine in ausgezeichnetem Zustand! Der vergangene Winter war nicht \u201egro\u00dfartig\u201c, aber viel besser als die der letzten Jahre. Die B\u00e4ume haben die K\u00e4lte und das Wasser bekommen, das sie ben\u00f6tigen, und profitieren von Eltons guter Pflege, besonders vom Herbstschnitt [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4936,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-4971","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tagebuch"],"_links":{"self":[{"href":"https:\/\/tragos.gr\/de\/wp-json\/wp\/v2\/posts\/4971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tragos.gr\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tragos.gr\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tragos.gr\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tragos.gr\/de\/wp-json\/wp\/v2\/comments?post=4971"}],"version-history":[{"count":0,"href":"https:\/\/tragos.gr\/de\/wp-json\/wp\/v2\/posts\/4971\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tragos.gr\/de\/wp-json\/wp\/v2\/media\/4936"}],"wp:attachment":[{"href":"https:\/\/tragos.gr\/de\/wp-json\/wp\/v2\/media?parent=4971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tragos.gr\/de\/wp-json\/wp\/v2\/categories?post=4971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tragos.gr\/de\/wp-json\/wp\/v2\/tags?post=4971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}