{"id":1615,"date":"2023-10-04T11:13:06","date_gmt":"2023-10-04T09:13:06","guid":{"rendered":"https:\/\/tragos.gr\/?page_id=1615"},"modified":"2025-10-06T15:51:33","modified_gmt":"2025-10-06T13:51:33","slug":"faq","status":"publish","type":"page","link":"https:\/\/tragos.gr\/de\/faq\/","title":{"rendered":"FAQ"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1615\" class=\"elementor elementor-1615 elementor-599\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-931b43f elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"931b43f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e89cb8c\" data-id=\"e89cb8c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1573bfc elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-widget elementor-widget-slides\" data-id=\"1573bfc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;arrows&quot;,&quot;transition&quot;:&quot;fade&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\r\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\" dir=\"ltr\" data-animation=\"fadeInUp\">\r\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-c30b51d swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"Main-Banner_Image-1\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-bf7a26d swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"Main-Banner_Image-3\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-09e744e swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"Main-Banner_Image-4\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-5b5c9f4 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"Main-Banner_Image-8\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-d1fcbed swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"Main-Banner_Image-5\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div>\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Previous slide\">\r\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Next slide\">\r\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-535379c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"535379c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b59f2cc\" data-id=\"b59f2cc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ccfcca elementor-widget elementor-widget-heading\" data-id=\"4ccfcca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">FAQ (H\u00e4ufig gestellte Fragen)<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-51f4517 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"51f4517\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d2cc89e elementor-widget elementor-widget-text-editor\" data-id=\"d2cc89e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span data-olk-copy-source=\"MessageBody\">Wie gut kennt Ihr Euch mit Oliven\u00f6l aus? Seid Ihr echte Experten oder gibt es Dinge, bei denen Ihr Euch nicht sicher seid? Wir hoffen jedenfalls, dass Ihr in unseren FAQs Neues und Interessantes finden werdet. Und nat\u00fcrlich k\u00f6nnt Ihr uns gerne jede weitere Frage, die von allgemeinem Interesse sein d\u00fcrfte, per E-Mail schicken.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-78ecc77 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"78ecc77\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6a63a5c\" data-id=\"6a63a5c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d70522d elementor-arrows-position-outside elementor--h-position-center elementor--v-position-middle elementor-widget elementor-widget-slides\" data-id=\"d70522d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\r\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\" dir=\"ltr\" data-animation=\"fadeInUp\">\r\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-e101d72 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"tragos-olives-harvest\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-bca9dac swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"tragos-extra-virgin-oil\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-4b4f7c6 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"Tragos-ProductsAllTogether-2025-deutch\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-69bd23d swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"tragos-procedure-Olive-oil-extra-virgin\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-6df0576 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"tragos-olive-oil-filtered\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div>\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Previous slide\">\r\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Next slide\">\r\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f9fecc9\" data-id=\"f9fecc9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-83a2664 elementor-widget elementor-widget-toggle\" data-id=\"83a2664\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h5 id=\"elementor-tab-title-1381\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1381\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Wann ist der richtige Zeitpunkt f\u00fcr die Ernte?<\/a>\n\t\t\t\t\t<\/h5>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1381\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1381\"><p>Der richtige Zeitpunkt f\u00fcr die Ernte ist, wenn die Oliven beginnen, sich gelb zu f\u00e4rben (die Olive ist zun\u00e4chst gr\u00fcn, wechselt dann zu gelb und schlie\u00dflich, wenn sie ihre volle Reife erreicht hat, wird sie dunkelviolett). Wenn die Oliven geerntet werden, w\u00e4hrend sie \u00fcberwiegend gr\u00fcn oder gelb sind, spricht man von einer \u201efr\u00fchen Ernte\u201c. Fr\u00fch geerntete Oliven ergeben m\u00f6glicherweise weniger Oliven\u00f6l, sind daf\u00fcr aber geschmackvoller, aromatischer und n\u00e4hrstoffreicher.<\/p><p>In unserer Gegend und f\u00fcr unsere Olivenbaumart (Manaki) liegt der richtige Erntezeitpunkt normalerweise in der zweiten Oktoberh\u00e4lfte.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h5 id=\"elementor-tab-title-1382\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1382\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Was ist ein extra natives Oliven\u00f6l?<\/a>\n\t\t\t\t\t<\/h5>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1382\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1382\"><p>Gem\u00e4\u00df der europ\u00e4ischen Gesetzgebung gibt es verschiedene Kategorien von Oliven\u00f6l (z. B. extra natives, natives usw). Um in einer bestimmten Kategorie vermarktet zu werden, m\u00fcssen die Eigenschaften des Oliven\u00f6ls die f\u00fcr diese Kategorie festgelegten Grenzwerte einhalten. Die verschiedenen Kategorien von Oliven\u00f6len werden nach Qualit\u00e4tsparametern eingestuft, die sich auf ihre <strong>physikalisch-chemischen Eigenschaften<\/strong> (u.a. S\u00e4uregehalt, Peroxidindex, UV232-Absorption) sowie ihre <strong>organoleptischen (sensorischen) Eigenschaften<\/strong>, wie Fruchtigkeit und die Abwesenheit organoleptischer M\u00e4ngel.<\/p><p>Extra natives Oliven\u00f6l ist die Kategorie mit der h\u00f6chsten Qualit\u00e4t. Aus organoleptischer Sicht weist es keine M\u00e4ngel auf und ist fruchtig. Sein S\u00e4uregehalt \u00fcberschreitet nicht 0,8%.<\/p><p>Mit Hilfe der Natur, achtsamer Pflege und fachkundiger Verarbeitung ist es uns bisher gelungen, extra native Oliven\u00f6le herzustellen.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h5 id=\"elementor-tab-title-1383\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1383\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Sind \"TRAGOS\" und \"TRAGOS and Friends\" sogenannte \"Premium\" Oliven\u00f6le?<\/a>\n\t\t\t\t\t<\/h5>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1383\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1383\"><p>Nein, denn es gibt keine &#8222;Premium&#8220;-Oliven\u00f6le. Wie bereits erw\u00e4hnt, sind die Kategorien der Oliven\u00f6le europaweit einheitlich festgelegt. In der geltenden Gesetzgebung, n\u00e4mlich der Verordnung (EU) 1308\/2013, erg\u00e4nzt durch die Verordnung (EU) 2104\/2022, werden &#8222;Premium&#8220;-Oliven\u00f6le nicht erw\u00e4hnt und somit auch keine Parameter daf\u00fcr festgelegt.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h5 id=\"elementor-tab-title-1384\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-1384\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Was ist Kaltextraktion und welche sind die Vorteile davon?<\/a>\n\t\t\t\t\t<\/h5>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1384\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-1384\"><p>Kaltextraktion ist ein Verfahren zur Herstellung von Oliven\u00f6l extra vergine. Dabei werden die Oliven mithilfe eines mechanischen Verfahrens zu einer Paste gepresst und anschlie\u00dfend wird das \u00d6l durch Zentrifugation von der Paste getrennt, ohne dass Hitze oder Chemikalien zum Einsatz kommen. Die w\u00e4hrend des Prozesses entstehende Temperatur darf 27 \u00b0C nicht \u00fcberschreiten und dieser Grenzwert gilt f\u00fcr alle Phasen des Prozesses, vom Mahlen der Oliven bis zur Zentrifugation der Paste.<\/p><p>Zu den Vorteilen der Kaltextraktions geh\u00f6ren die Erhaltung des Geschmacks, des Aromas und des N\u00e4hrwerts der Oliven sowie die Erhaltung der Antioxidantien und Vitamine, die nat\u00fcrlicherweise in Oliven vorkommen.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d5405e6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d5405e6\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-903a48b\" data-id=\"903a48b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e649edc elementor-widget elementor-widget-toggle\" data-id=\"e649edc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h5 id=\"elementor-tab-title-2411\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2411\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Ist Oliven\u00f6l zum Braten geeignet?<\/a>\n\t\t\t\t\t<\/h5>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2411\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2411\"><p>Ja, Oliven\u00f6l ist zum Braten geeignet. Tats\u00e4chlich ist dies in Griechenland auch sehr verbreitet. Oliven\u00f6l hat einen hohen Rauchpunkt von etwa 210 \u00b0C, was bedeutet, dass es auf eine Temperatur erhitzt werden kann, die hoch genug ist, um Lebensmittel sicher zu br\u00e4unen und knusprig zu machen. Es kann sowohl zum Kochen bei niedriger als auch bei hoher Hitze verwendet werden und eignet sich gut f\u00fcr die meisten Arten des Frittierens und Sautierens.<\/p><p>Allerdings sollte man nicht mehr als zweimal eine gewisse Menge Oliven\u00f6l zum Braten verwenden, da sonst giftige Substanzen entstehen k\u00f6nnten.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h5 id=\"elementor-tab-title-2412\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2412\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Wie soll Oliven\u00f6l gelagert werden?<\/a>\n\t\t\t\t\t<\/h5>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2412\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2412\"><p>Oliven\u00f6l bleibt lange frisch, wenn bestimmte Grunds\u00e4tze beachtet werden: Es muss k\u00fchl und dunkel gelagert werden und darf nicht mit Luft in Ber\u00fchrung kommen. Ein Keller ist somit der ideale Lagerungsort f\u00fcr ein solches Lebensmittel.<\/p><p>Unser Ziel ist es, das Oliven\u00f6l so schnell wie m\u00f6glich nach der Ernte an unsere Kunden zu liefern. So wird das Oliven\u00f6l unter k\u00fchlen Bedingungen hergestellt, verarbeitet, gelagert und transportiert und kommt frisch bei unseren Kunden an.<\/p><p><span lang=\"DE\" data-olk-copy-source=\"MessageBody\">Es entspricht der Praxis vieler Familien in Griechenland, sich &#8222;das \u00d6l des Jahres&#8220; (&#8222;<\/span>\u03c4\u03bf \u03bb\u03ac\u03b4\u03b9 \u03c4\u03b7\u03c2 \u03c7\u03c1\u03bf\u03bd\u03b9\u03ac\u03c2&#8220;<span lang=\"DE\">) gleich nach der Ernte zu besorgen. So erh\u00e4lt man das Oliven\u00f6l frisch und kann sicherstellen, dass es bis zu seinem Verbrauch richtig gelagert wird.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h5 id=\"elementor-tab-title-2413\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-2413\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Warum verwendet Ihr dunkle statt durchsichtiger Flaschen (so dass man auch die Farbe des Oliven\u00f6ls sehen kann)?<\/a>\n\t\t\t\t\t<\/h5>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2413\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-2413\"><p>Wir verwenden dunkle Flaschen, da das \u00d6l durch Lichteinwirkung zersetzt werden und seinen Geschmack, sein Aroma und seine gesundheitlichen Vorteile verlieren kann. Dunkle Flaschen sch\u00fctzen das \u00d6l vor Lichteinwirkung und bewahren so seine Qualit\u00e4t.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h5 id=\"elementor-tab-title-2414\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-2414\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Warum f\u00fcllt Ihr Eure \u00d6le in gro\u00dfe Flaschen bzw. Beh\u00e4lter ab?<\/a>\n\t\t\t\t\t<\/h5>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2414\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-2414\"><p>Typischerweise wird feines Oliven\u00f6l in kleine Flaschen abgef\u00fcllt. Allerdings ist Oliven\u00f6l kein Parf\u00fcm, sondern ein Lebensmittel, das t\u00e4glich verzehrt werden sollte (empfohlene Tagesdosis: 10-15 ml\/Tag). Deshalb machen kleine Flaschen wenig Sinn.<\/p><p>Wir finden auch, dass das Bef\u00fcllen gr\u00f6\u00dferer Beh\u00e4lter umweltfreundlicher ist. Dadurch wird der Verbrauch von Energie und nat\u00fcrlichen Ressourcen (z. B. bei der Herstellung und dem Transport von Flaschen, bei Verpackungen etc.) reduziert und es entsteht weniger Abfall.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-39046cb\" data-id=\"39046cb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-42d8dbd elementor-arrows-position-outside elementor--h-position-center elementor--v-position-middle elementor-widget elementor-widget-slides\" data-id=\"42d8dbd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\r\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\" dir=\"ltr\" data-animation=\"fadeInUp\">\r\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-e101d72 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"tragos-frying-olive-oil\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-1397767 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"Tragos-Prasentation_Aktuelles-3\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-4523b39 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"Tragos-Olivenol-1LT-bottle-2024-Front-Light-DE\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-40abfb1 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"TragosAndFriends-Olivenol-BIO-3LT-2024-Front-DE\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-6e3ac24 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"TragosAndFriends-Olivenol-3LT-2024-Front-DE\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div>\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Previous slide\">\r\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Next slide\">\r\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c513fa0 elementor-align-right elementor-widget elementor-widget-button\" data-id=\"c513fa0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/tragos.gr\/de\/tragospedia\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">ZUR\u00dcCK ZU TRAGOSPEDIA<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>FAQ (H\u00e4ufig gestellte Fragen) Wie gut kennt Ihr Euch mit Oliven\u00f6l aus? Seid Ihr echte Experten oder gibt es Dinge, bei denen Ihr Euch nicht sicher seid? Wir hoffen jedenfalls, dass Ihr in unseren FAQs Neues und Interessantes finden werdet. Und nat\u00fcrlich k\u00f6nnt Ihr uns gerne jede weitere Frage, die von allgemeinem Interesse sein d\u00fcrfte, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-1615","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/tragos.gr\/de\/wp-json\/wp\/v2\/pages\/1615","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tragos.gr\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tragos.gr\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tragos.gr\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tragos.gr\/de\/wp-json\/wp\/v2\/comments?post=1615"}],"version-history":[{"count":0,"href":"https:\/\/tragos.gr\/de\/wp-json\/wp\/v2\/pages\/1615\/revisions"}],"wp:attachment":[{"href":"https:\/\/tragos.gr\/de\/wp-json\/wp\/v2\/media?parent=1615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}